{"id":2241,"date":"2022-08-11T14:47:53","date_gmt":"2022-08-11T14:47:53","guid":{"rendered":"https:\/\/nunoa.cl\/nunoapatrimonial\/?page_id=2241"},"modified":"2024-01-09T18:42:28","modified_gmt":"2024-01-09T18:42:28","slug":"casona-torres","status":"publish","type":"page","link":"https:\/\/nunoa.cl\/nunoapatrimonial\/casona-torres\/","title":{"rendered":"CASONA TORRES"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2241\" class=\"elementor elementor-2241\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2af8feb elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"2af8feb\" data-element_type=\"section\" data-e-type=\"section\" id=\"republicana\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bea3cec\" data-id=\"bea3cec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4a9a68 elementor-widget elementor-widget-spacer\" data-id=\"d4a9a68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-897b110 eael-dual-header-content-align-center elementor-invisible elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"897b110\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"Prehispanica\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<h1 class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">CASONA<\/span> <span class=\"eael-dch-title-text\">TORRES<\/span><\/h1>\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1932ebe elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"1932ebe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-96ed1c6\" data-id=\"96ed1c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-429d9e6 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"429d9e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"680\" height=\"436\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/CERs_dlW8AAYCwT.jpg\" class=\"attachment-full size-full wp-image-2682\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/CERs_dlW8AAYCwT.jpg 680w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/CERs_dlW8AAYCwT-300x192.jpg 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/CERs_dlW8AAYCwT-600x385.jpg 600w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ad8cd2 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3ad8cd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La necesidad de contar con un edificio m\u00e1s grande, lleva a su directora\u00a0<strong>Florencia Barrios Tirado<\/strong>\u00a0a \u00a0comprar la propiedad vecina que inclu\u00eda la mansi\u00f3n Torres y su parque, adquisici\u00f3n que se concreta en 1948. La ceremonia de inauguraci\u00f3n estuvo encabezada por los directivos del liceo, el\u00a0<strong>Presidente Gabriel Gonz\u00e1lez Videla<\/strong>\u00a0y el rector de la Universidad de Chile,\u00a0<strong>Juvenal Hern\u00e1ndez<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-77d3a1f\" data-id=\"77d3a1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-736b45c elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"736b45c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En 1924 el arquitecto\u00a0<strong>Josu\u00e9 Smith Solar<\/strong>\u00a0(1867-1938) fue el encargado de idear los planos de la residencia en la Avenida Irarr\u00e1zaval con una marcada tendencia Tudor.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c317d2 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"6c317d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Pedro Torres Ibieta<\/strong>, un hombre de negocios de Valpara\u00edso que ejerc\u00eda como\u00a0<strong>Presidente del Banco de Chile<\/strong>\u00a0y director de otras tantas instituciones bancarias; reconocido adem\u00e1s por ser el impulsor de la construcci\u00f3n del Teatro Central, una de las salas de conciertos m\u00e1s importantes del pa\u00eds fue quien le encargo a Smith Solar la contrucci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-159c39c elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"159c39c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Smith Solar levant\u00f3 una edificaci\u00f3n de concreto armado de m\u00e1s de mil metros cuadrados, con dos niveles m\u00e1s una alta techumbre. El estilo Tudor fue realzado por el cuidadoso tratamiento de los muros con alba\u00f1iler\u00eda a la vista y estuco, la incorporaci\u00f3n de paneles vidriados, techos a dos aguas con decorativos enmaderados, un torre\u00f3n, diversa herrer\u00eda ornamental y altas chimeneas que sobrepasaban la cubierta de tejas de cedro.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24086b6 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"24086b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La propiedad contaba con un enorme parque con espejos de agua, parrones, zonas de descanso y una piscina. En \u00e9l se ubicaron estrat\u00e9gicamente dependencias de servicio, cocheras, una casa secundaria y un pabell\u00f3n de porter\u00eda en la esquina de Brown Norte con Irarr\u00e1zaval, donde se situ\u00f3 un port\u00f3n de fierro para el ingreso de coches.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e477f26 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"e477f26\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los problemas econ\u00f3micos de los descendientes del se\u00f1or Torres, los obligan a lotear la extensa propiedad en 1947. Ese mismo a\u00f1o el emblem\u00e1tico\u00a0<strong>Liceo Experimental Manuel de Salas\u00a0<\/strong>de la<strong>\u00a0Universidad de Chile<\/strong>, decide comprar un peque\u00f1o terreno en el n\u00famero 3780 de la avenida Irarr\u00e1zaval para instalar las nuevas dependencias de la instituci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a36fca3 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"a36fca3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71a8236\" data-id=\"71a8236\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-470dc4b elementor-widget elementor-widget-spacer\" data-id=\"470dc4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-04d1576 elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"04d1576\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-0be6bce\" data-id=\"0be6bce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fc9824 eael-dual-header-content-align-center elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"2fc9824\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<h1 class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">Casona<\/span> <span class=\"eael-dch-title-text\">Torres<\/span><\/h1><div class=\"eael-dch-separator-wrap\"><span class=\"separator-one\"><\/span>\n\t\t\t<span class=\"separator-two\"><\/span><\/div>\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6195448 elementor-widget elementor-widget-image\" data-id=\"6195448\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/casona-torres\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000002-1-300x300.jpg\" class=\"attachment-medium size-medium wp-image-2019\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000002-1-300x300.jpg 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000002-1-150x150.jpg 150w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000002-1-768x768.jpg 768w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000002-1-80x80.jpg 80w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000002-1-600x600.jpg 600w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000002-1-100x100.jpg 100w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000002-1.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5da6f02\" data-id=\"5da6f02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db0065c eael-dual-header-content-align-center elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"db0065c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<h1 class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">Inst Chileno<\/span> <span class=\"eael-dch-title-text\">-Brit\u00e1nico<\/span><\/h1><div class=\"eael-dch-separator-wrap\"><span class=\"separator-one\"><\/span>\n\t\t\t<span class=\"separator-two\"><\/span><\/div>\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40d9a78 elementor-widget elementor-widget-image\" data-id=\"40d9a78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/inst-chileno-britanico\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/brit3-300x300.jpg\" class=\"attachment-medium size-medium wp-image-2047\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/brit3-300x300.jpg 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/brit3-150x150.jpg 150w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/brit3-768x768.jpg 768w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/brit3-80x80.jpg 80w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/brit3-600x600.jpg 600w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/brit3-100x100.jpg 100w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/brit3.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-c775aab\" data-id=\"c775aab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d799b1 eael-dual-header-content-align-center elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"0d799b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<h1 class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">Palacio<\/span> <span class=\"eael-dch-title-text\">Garc\u00eda<\/span><\/h1><div class=\"eael-dch-separator-wrap\"><span class=\"separator-one\"><\/span>\n\t\t\t<span class=\"separator-two\"><\/span><\/div>\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f0cbd6 elementor-widget elementor-widget-image\" data-id=\"7f0cbd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/palacio-garcia\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000003-1-300x300.jpg\" class=\"attachment-medium size-medium wp-image-2023\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000003-1-300x300.jpg 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000003-1-150x150.jpg 150w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000003-1-768x768.jpg 768w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000003-1-80x80.jpg 80w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000003-1-600x600.jpg 600w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000003-1-100x100.jpg 100w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000003-1.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5741a24\" data-id=\"5741a24\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b58ef4 eael-dual-header-content-align-center elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"8b58ef4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<h1 class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">Quinta<\/span> <span class=\"eael-dch-title-text\">Hamburgo<\/span><\/h1><div class=\"eael-dch-separator-wrap\"><span class=\"separator-one\"><\/span>\n\t\t\t<span class=\"separator-two\"><\/span><\/div>\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b16af0 elementor-widget elementor-widget-image\" data-id=\"5b16af0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/quinta-hamburgo\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000004-1-300x300.jpg\" class=\"attachment-medium size-medium wp-image-2027\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000004-1-300x300.jpg 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000004-1-150x150.jpg 150w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000004-1-768x768.jpg 768w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000004-1-80x80.jpg 80w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000004-1-600x600.jpg 600w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000004-1-100x100.jpg 100w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000004-1.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1c73cb9\" data-id=\"1c73cb9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2bad96 eael-dual-header-content-align-center elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"f2bad96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<h1 class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">Palacio <\/span> <span class=\"eael-dch-title-text\">Ort\u00fazar<\/span><\/h1><div class=\"eael-dch-separator-wrap\"><span class=\"separator-one\"><\/span>\n\t\t\t<span class=\"separator-two\"><\/span><\/div>\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0270e9d elementor-widget elementor-widget-image\" data-id=\"0270e9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/palacio-ortuzar\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000005-5-300x300.jpg\" class=\"attachment-medium size-medium wp-image-2029\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000005-5-300x300.jpg 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000005-5-150x150.jpg 150w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000005-5-768x768.jpg 768w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000005-5-80x80.jpg 80w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000005-5-600x600.jpg 600w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000005-5-100x100.jpg 100w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000005-5.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef3ab31 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"ef3ab31\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-194e77c\" data-id=\"194e77c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a89958b eael-dual-header-content-align-center elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"a89958b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<h1 class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">Mezquita<\/span> <span class=\"eael-dch-title-text\">As -Salam<\/span><\/h1><div class=\"eael-dch-separator-wrap\"><span class=\"separator-one\"><\/span>\n\t\t\t<span class=\"separator-two\"><\/span><\/div>\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3441b30 elementor-widget elementor-widget-image\" data-id=\"3441b30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/mezquita-as-salam\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000001-1-300x300.jpg\" class=\"attachment-medium size-medium wp-image-2015\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000001-1-300x300.jpg 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000001-1-150x150.jpg 150w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000001-1-768x768.jpg 768w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000001-1-80x80.jpg 80w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000001-1-600x600.jpg 600w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000001-1-100x100.jpg 100w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000001-1.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-404345b\" data-id=\"404345b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7de6681 eael-dual-header-content-align-center elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"7de6681\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<h1 class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">Edificio<\/span> <span class=\"eael-dch-title-text\">Consistorial<\/span><\/h1><div class=\"eael-dch-separator-wrap\"><span class=\"separator-one\"><\/span>\n\t\t\t<span class=\"separator-two\"><\/span><\/div>\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83d1a37 elementor-widget elementor-widget-image\" data-id=\"83d1a37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/edificio-consistorial\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000006-300x300.jpg\" class=\"attachment-medium size-medium wp-image-2037\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000006-300x300.jpg 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000006-150x150.jpg 150w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000006-768x768.jpg 768w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000006-80x80.jpg 80w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000006-600x600.jpg 600w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000006-100x100.jpg 100w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000006.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3792619\" data-id=\"3792619\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53a561c eael-dual-header-content-align-center elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"53a561c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<h1 class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\"> Iglesia<\/span> <span class=\"eael-dch-title-text\">Ortodoxa Rusa<\/span><\/h1><div class=\"eael-dch-separator-wrap\"><span class=\"separator-one\"><\/span>\n\t\t\t<span class=\"separator-two\"><\/span><\/div>\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a74e65 elementor-widget elementor-widget-image\" data-id=\"4a74e65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/iglesia-ortodoxa-rusa\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000007-300x300.jpg\" class=\"attachment-medium size-medium wp-image-2038\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000007-300x300.jpg 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000007-150x150.jpg 150w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000007-768x768.jpg 768w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000007-80x80.jpg 80w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000007-600x600.jpg 600w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000007-100x100.jpg 100w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000007.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6b5160e\" data-id=\"6b5160e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c52f89c eael-dual-header-content-align-center elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"c52f89c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<h1 class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">Iglesia<\/span> <span class=\"eael-dch-title-text\">Ortodoxa Griega<\/span><\/h1><div class=\"eael-dch-separator-wrap\"><span class=\"separator-one\"><\/span>\n\t\t\t<span class=\"separator-two\"><\/span><\/div>\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-799333a elementor-widget elementor-widget-image\" data-id=\"799333a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/iglesia-ortodoxa-griega\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000008-300x300.jpg\" class=\"attachment-medium size-medium wp-image-2042\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000008-300x300.jpg 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000008-150x150.jpg 150w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000008-768x768.jpg 768w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000008-80x80.jpg 80w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000008-600x600.jpg 600w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000008-100x100.jpg 100w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/0000008.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-466d7ba elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"466d7ba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b50ef1f\" data-id=\"b50ef1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e03cbb eael-dual-header-content-align-center elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"2e03cbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<h1 class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">Instituto<\/span> <span class=\"eael-dch-title-text\">de Salud P\u00fablica<\/span><\/h1><div class=\"eael-dch-separator-wrap\"><span class=\"separator-one\"><\/span>\n\t\t\t<span class=\"separator-two\"><\/span><\/div>\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff5aa4c elementor-widget elementor-widget-image\" data-id=\"ff5aa4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/instituto-de-salud-publica\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Capa-2-300x300.jpg\" class=\"attachment-medium size-medium wp-image-2053\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Capa-2-300x300.jpg 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Capa-2-150x150.jpg 150w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Capa-2-768x768.jpg 768w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Capa-2-80x80.jpg 80w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Capa-2-600x600.jpg 600w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Capa-2-100x100.jpg 100w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Capa-2.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f23b404\" data-id=\"f23b404\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18991e2 eael-dual-header-content-align-center elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"18991e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<h1 class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">Teatro<\/span> <span class=\"eael-dch-title-text\">UC<\/span><\/h1><div class=\"eael-dch-separator-wrap\"><span class=\"separator-one\"><\/span>\n\t\t\t<span class=\"separator-two\"><\/span><\/div>\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12c67df elementor-widget elementor-widget-image\" data-id=\"12c67df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/teatro-uc\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Capa-1-300x300.jpg\" class=\"attachment-medium size-medium wp-image-2051\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Capa-1-300x300.jpg 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Capa-1-150x150.jpg 150w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Capa-1-768x768.jpg 768w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Capa-1-80x80.jpg 80w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Capa-1-600x600.jpg 600w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Capa-1-100x100.jpg 100w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Capa-1.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dbadffa\" data-id=\"dbadffa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-917622b eael-dual-header-content-align-center elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"917622b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<h1 class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">Monasterio<\/span> <span class=\"eael-dch-title-text\">San Jos\u00e9<\/span><\/h1><div class=\"eael-dch-separator-wrap\"><span class=\"separator-one\"><\/span>\n\t\t\t<span class=\"separator-two\"><\/span><\/div>\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9aec77a elementor-widget elementor-widget-image\" data-id=\"9aec77a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/monasterio-san-jose\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Monasterio-300x300.jpg\" class=\"attachment-medium size-medium wp-image-2046\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Monasterio-300x300.jpg 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Monasterio-150x150.jpg 150w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Monasterio-768x768.jpg 768w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Monasterio-80x80.jpg 80w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Monasterio-600x600.jpg 600w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Monasterio-100x100.jpg 100w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/Monasterio.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a082b5 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"7a082b5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ba3af13\" data-id=\"ba3af13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e7e0b5 elementor-widget elementor-widget-spacer\" data-id=\"5e7e0b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-baba1d9 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"baba1d9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50a2b25\" data-id=\"50a2b25\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a18a149 elementor-widget elementor-widget-spacer\" data-id=\"a18a149\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-795e9a2 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"795e9a2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d3d641\" data-id=\"0d3d641\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5d3176 elementor-widget elementor-widget-heading\" data-id=\"c5d3176\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00daltimas publicaciones<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a066e96 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"a066e96\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ba63ba\" data-id=\"3ba63ba\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0cefd4c elementor-grid-eael-col-4 elementor-grid-tablet-eael-col-2 elementor-grid-mobile-eael-col-1 elementor-widget elementor-widget-eael-post-grid\" data-id=\"0cefd4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;eael_post_grid_columns&quot;:&quot;eael-col-4&quot;,&quot;eael_post_grid_columns_tablet&quot;:&quot;eael-col-2&quot;,&quot;eael_post_grid_columns_mobile&quot;:&quot;eael-col-1&quot;}\" data-widget_type=\"eael-post-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"eael-post-grid-0cefd4c\" class=\"eael-post-grid-container\">\n            <div class=\"eael-post-grid eael-post-appender eael-post-appender-0cefd4c eael-post-grid-style-one\" data-layout-mode=\"grid\"><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-247 category-historia-noticias tags-business-food-photography\" data-id=\"247\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-angle-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/el-origen-indigena-del-nombre-nunoa\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"247\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2018\/02\/mc0018794-e1664409879528-300x247.jpg\" class=\"attachment-medium size-medium wp-image-1859\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2018\/02\/mc0018794-e1664409879528-300x247.jpg 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2018\/02\/mc0018794-e1664409879528.jpg 451w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h3 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/el-origen-indigena-del-nombre-nunoa\/\" title=\"El Origen Ind\u00edgena del nombre \u00d1u\u00f1oa\">El Origen Ind\u00edgena del nombre \u00d1u\u00f1oa<\/a><\/h3><\/header><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-256 category-historia-noticias-patrimonio tags-business-food-photography\" data-id=\"256\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-angle-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/el-arte-de-gregorio-de-la-fuente\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"216\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2018\/02\/e343c7dbce18df297b34421d928457cb-300x216.jpg\" class=\"attachment-medium size-medium wp-image-1837\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2018\/02\/e343c7dbce18df297b34421d928457cb-300x216.jpg 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2018\/02\/e343c7dbce18df297b34421d928457cb-1024x736.jpg 1024w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2018\/02\/e343c7dbce18df297b34421d928457cb-768x552.jpg 768w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2018\/02\/e343c7dbce18df297b34421d928457cb-600x431.jpg 600w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2018\/02\/e343c7dbce18df297b34421d928457cb.jpg 1077w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h3 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/el-arte-de-gregorio-de-la-fuente\/\" title=\"El Arte de Gregorio de la Fuente\">El Arte de Gregorio de la Fuente<\/a><\/h3><\/header><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-4435 category-historia-noticias\" data-id=\"4435\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-angle-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/fiesta18\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"134\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/09\/Charton_Ernest_-_18_de_septiembre_en_el_Campo_de_Marte_1845_f2-e1663248952536-300x134.jpg\" class=\"attachment-medium size-medium wp-image-4439\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/09\/Charton_Ernest_-_18_de_septiembre_en_el_Campo_de_Marte_1845_f2-e1663248952536-300x134.jpg 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/09\/Charton_Ernest_-_18_de_septiembre_en_el_Campo_de_Marte_1845_f2-e1663248952536-768x344.jpg 768w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/09\/Charton_Ernest_-_18_de_septiembre_en_el_Campo_de_Marte_1845_f2-e1663248952536-600x268.jpg 600w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/09\/Charton_Ernest_-_18_de_septiembre_en_el_Campo_de_Marte_1845_f2-e1663248952536.jpg 990w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h3 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/fiesta18\/\" title=\"El Origen de la Fiesta del 18\">El Origen de la Fiesta del 18<\/a><\/h3><\/header><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-537 category-historia-memoria-patrimonio\" data-id=\"537\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-angle-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/dia_los_patrimonios-_en_nunoa\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/05\/DPC17-1200x900-1-300x225.jpg\" class=\"attachment-medium size-medium wp-image-1763\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/05\/DPC17-1200x900-1-300x225.jpg 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/05\/DPC17-1200x900-1-1024x768.jpg 1024w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/05\/DPC17-1200x900-1-768x576.jpg 768w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/05\/DPC17-1200x900-1-600x450.jpg 600w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/05\/DPC17-1200x900-1.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h3 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/nunoa.cl\/nunoapatrimonial\/dia_los_patrimonios-_en_nunoa\/\" title=\"D\u00eda de los Patrimonios en \u00d1u\u00f1oa\">D\u00eda de los Patrimonios en \u00d1u\u00f1oa<\/a><\/h3><\/header><\/div><\/div>\n        <\/div>\n    <\/article><\/div>\n            <div class=\"clearfix\"><\/div>\n        <\/div>            <div class=\"eael-load-more-button-wrap\">\n                <button class=\"eael-load-more-button\" id=\"eael-load-more-btn-0cefd4c\" data-widget-id=\"0cefd4c\" data-widget=\"0cefd4c\" data-page-id=\"2241\" data-template=\"{&quot;dir&quot;:&quot;lite&quot;,&quot;file_name&quot;:&quot;one.php&quot;,&quot;name&quot;:&quot;Post-Grid&quot;}\" data-class=\"Essential_Addons_Elementor\\Elements\\Post_Grid\" data-layout=\"grid\" data-page=\"1\" data-args=\"orderby=date&amp;order=desc&amp;ignore_sticky_posts=1&amp;post_status=publish&amp;posts_per_page=4&amp;offset=0&amp;post_type=post&amp;tax_query%5B0%5D%5Btaxonomy%5D=category&amp;tax_query%5B0%5D%5Bfield%5D=term_id&amp;tax_query%5B0%5D%5Bterms%5D%5B0%5D=42&amp;tax_query%5Brelation%5D=AND\" data-max-page=\"3\">\n                    <span class=\"eael-btn-loader button__loader\"><\/span>\n                    <span class=\"eael_load_more_text\">Conocer m\u00e1s<\/span>\n                <\/button>\n            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-630a1b5 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"630a1b5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eec5f83\" data-id=\"eec5f83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27724fa eael-dual-header-content-align-center elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"27724fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<h2 class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">LINKS<\/span> <span class=\"eael-dch-title-text\">DE INTER\u00c9S<\/span><\/h2>\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba62e1a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"ba62e1a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0e93b65\" data-id=\"0e93b65\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0bd925 elementor-widget elementor-widget-image\" data-id=\"d0bd925\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.nunoa.cl\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"122\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/LOGO-1-300x122.png\" class=\"attachment-medium size-medium wp-image-1080\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/LOGO-1-300x122.png 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/LOGO-1-1024x416.png 1024w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/LOGO-1-768x312.png 768w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/LOGO-1-1536x625.png 1536w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/LOGO-1-2048x833.png 2048w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/LOGO-1-600x244.png 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-83b2b46\" data-id=\"83b2b46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8def44c elementor-widget elementor-widget-image\" data-id=\"8def44c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.ccn.cl\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"122\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/ccn-300x122.png\" class=\"attachment-medium size-medium wp-image-1079\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/ccn-300x122.png 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/ccn-1024x416.png 1024w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/ccn-768x312.png 768w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/ccn-1536x625.png 1536w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/ccn-2048x833.png 2048w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/ccn-600x244.png 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-668e27d\" data-id=\"668e27d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f062280 elementor-widget elementor-widget-image\" data-id=\"f062280\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nunoapanorama.cl\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"122\" src=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/LOGO-1-2-300x122.png\" class=\"attachment-medium size-medium wp-image-1090\" alt=\"\" srcset=\"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/LOGO-1-2-300x122.png 300w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/LOGO-1-2-1024x416.png 1024w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/LOGO-1-2-768x312.png 768w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/LOGO-1-2-1536x625.png 1536w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/LOGO-1-2-2048x833.png 2048w, https:\/\/nunoa.cl\/nunoapatrimonial\/wp-content\/uploads\/2022\/08\/LOGO-1-2-600x244.png 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b20b27 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"5b20b27\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-afb039e\" data-id=\"afb039e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>CASONA TORRES La necesidad de contar con un edificio m\u00e1s grande, lleva a su directora\u00a0Florencia Barrios Tirado\u00a0a \u00a0comprar la propiedad vecina que inclu\u00eda la mansi\u00f3n Torres y su parque, adquisici\u00f3n que se concreta en 1948. La ceremonia de inauguraci\u00f3n estuvo encabezada por los directivos del liceo, el\u00a0Presidente Gabriel Gonz\u00e1lez Videla\u00a0y el rector de la Universidad de Chile,\u00a0Juvenal Hern\u00e1ndez. En 1924 el arquitecto\u00a0Josu\u00e9 Smith Solar\u00a0(1867-1938) fue el encargado de idear los planos de la residencia en la Avenida Irarr\u00e1zaval con una marcada tendencia Tudor. Pedro Torres Ibieta, un hombre de negocios de Valpara\u00edso que ejerc\u00eda como\u00a0Presidente del Banco de Chile\u00a0y director de otras tantas instituciones bancarias; reconocido adem\u00e1s por ser el impulsor de la construcci\u00f3n del Teatro Central, una de las salas de conciertos m\u00e1s importantes del pa\u00eds fue quien le encargo a Smith Solar la contrucci\u00f3n. Smith Solar levant\u00f3 una edificaci\u00f3n de concreto armado de m\u00e1s de mil metros cuadrados, con dos niveles m\u00e1s una alta techumbre. El estilo Tudor fue realzado por el cuidadoso tratamiento de los muros con alba\u00f1iler\u00eda a la vista y estuco, la incorporaci\u00f3n de paneles vidriados, techos a dos aguas con decorativos enmaderados, un torre\u00f3n, diversa herrer\u00eda ornamental y altas chimeneas que sobrepasaban la cubierta de tejas de cedro. La propiedad contaba con un enorme parque con espejos de agua, parrones, zonas de descanso y una piscina. En \u00e9l se ubicaron estrat\u00e9gicamente dependencias de servicio, cocheras, una casa secundaria y un pabell\u00f3n de porter\u00eda en la esquina de Brown Norte con Irarr\u00e1zaval, donde se situ\u00f3 un port\u00f3n de fierro para el ingreso de coches. Los problemas econ\u00f3micos de los descendientes del se\u00f1or Torres, los obligan a lotear la extensa propiedad en 1947. Ese mismo a\u00f1o el emblem\u00e1tico\u00a0Liceo Experimental Manuel de Salas\u00a0de la\u00a0Universidad de Chile, decide comprar un peque\u00f1o terreno en el n\u00famero 3780 de la avenida Irarr\u00e1zaval para instalar las nuevas dependencias de la instituci\u00f3n. Casona Torres Inst Chileno -Brit\u00e1nico Palacio Garc\u00eda Quinta Hamburgo Palacio Ort\u00fazar Mezquita As -Salam Edificio Consistorial Iglesia Ortodoxa Rusa Iglesia Ortodoxa Griega Instituto de Salud P\u00fablica Teatro UC Monasterio San Jos\u00e9 \u00daltimas publicaciones D\u00eda de los Patrimonios en \u00d1u\u00f1oa Villa Ol\u00edmpica (Operaci\u00f3n Albania) Observatorio de Memoria y Derechos Humanos Los Carros de Sangre y Tranv\u00edas en \u00d1u\u00f1oa Conocer m\u00e1s LINKS DE INTER\u00c9S<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-2241","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"appart_350x360":false,"appart_350x400":false,"appart_80x80":false,"appart_570x340":false,"appart_100x80":false,"appart_750x400":false,"alm-thumbnail":false},"uagb_author_info":{"display_name":"ADMIN","author_link":"https:\/\/nunoa.cl\/nunoapatrimonial\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"CASONA TORRES La necesidad de contar con un edificio m\u00e1s grande, lleva a su directora\u00a0Florencia Barrios Tirado\u00a0a \u00a0comprar la propiedad vecina que inclu\u00eda la mansi\u00f3n Torres y su parque, adquisici\u00f3n que se concreta en 1948. La ceremonia de inauguraci\u00f3n estuvo encabezada por los directivos del liceo, el\u00a0Presidente Gabriel Gonz\u00e1lez Videla\u00a0y el rector de la Universidad&hellip;","_links":{"self":[{"href":"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-json\/wp\/v2\/pages\/2241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-json\/wp\/v2\/comments?post=2241"}],"version-history":[{"count":0,"href":"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-json\/wp\/v2\/pages\/2241\/revisions"}],"wp:attachment":[{"href":"https:\/\/nunoa.cl\/nunoapatrimonial\/wp-json\/wp\/v2\/media?parent=2241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}